{"id":2825,"date":"2016-02-03T18:21:37","date_gmt":"2016-02-03T16:21:37","guid":{"rendered":"http:\/\/www.auto-coaching.fr\/?p=2825"},"modified":"2016-02-05T12:41:43","modified_gmt":"2016-02-05T10:41:43","slug":"un-secret-de-millionnaire-2-2","status":"publish","type":"post","link":"https:\/\/auto-coaching.fr\/index.php\/un-secret-de-millionnaire-2-2\/","title":{"rendered":"Un secret de millionnaire (2\/2)"},"content":{"rendered":"<p>Mercredi dernier nous avons eu de l\u2019animation\u00a0: <a href=\"http:\/\/www.auto-coaching.fr\/index.php\/un-secret-de-millionnaire-1-2\/\">plusieurs dizaines de commentaires\u00a0!<\/a> Il semble que la question d\u2019argent int\u00e9resse beaucoup de monde, m\u00eame si souvent, on me ram\u00e8ne vers le fameux \u00abL\u2019argent ne fait pas le Bonheur\u00a0!\u00bb.<\/p>\n<p>C\u2019est tr\u00e8s juste. L\u2019argent n\u2019est pas g\u00e9n\u00e9rateur, mais amplificateur. Il amplifie ce que vous avez en vous. Il donne le pouvoir \u00e0 votre Etre de se manifester davantage. C\u2019est pour cette raison qu\u2019il est pr\u00e9f\u00e9rable d\u2019\u00e9viter la richesse quand on est malheureux. Mais si vous \u00eates sur le chemin du Bonheur, laissez-vous tenter par les opportunit\u00e9s et les id\u00e9es qui rapportent\u00a0!<\/p>\n<p>Ainsi, les livres, les formations, les articles, les propositions qui vous parlent d\u2019argent, n\u2019ont rien de malsain. Tout d\u00e9pend de ce que vous faites avec votre argent et du jugement que vous portez sur cet usage. C\u2019est pour cette raison que lorsqu\u2019une personne me reproche de parler d\u2019argent de fa\u00e7on d\u00e9complex\u00e9e, je l\u2019interroge sur l\u2019usage qu\u2019elle en ferait si elle \u00e9tait riche&#8230; C\u2019est alors que nous changeons de sujet\u00a0!<\/p>\n<p>Dans la suite de cet article, lorsque j\u2019emploierai le mot \u00abmillionnaire\u00bb,\u00a0 ce sera pour d\u00e9signer une personne qui a construit et qui construit encore sa fortune de fa\u00e7on honn\u00eate. Nous sommes dans un cadre de D\u00e9veloppement Personnel, et DANS CE CADRE PRECIS, parler d\u2019argent, d\u2019ambition, de r\u00e9ussite, de succ\u00e8s&#8230; de fa\u00e7on humaniste est une bonne pratique. Si vous pensez qu\u2019un bon millionnaire, g\u00e9n\u00e9reux, amoureux, bosseur, amical, \u00e7a n\u2019existe pas\u00a0! Si vous pensez qu\u2019ils sont tous pourris jusqu\u2019\u00e0 l\u2019os, cet article n\u2019est pas pour vous.<\/p>\n<p>Je ne dis pas que les millionnaires sont obligatoirement de bonnes personnes. Je dis juste qu\u2019il y a de bonnes et de mauvaises personnes chez les pauvres comme chez les riches, et que l\u2019argent n\u2019est pas responsable d\u2019un changement profond. Si vous \u00eates une bonne personne, rassurez-vous\u00a0! Vous utiliserez vos millions pour rendre le monde meilleur.<\/p>\n<p>Beaucoup de gens peuvent imaginer ce qu\u2019ils feraient d\u2019un million d\u2019euros s\u2019il leur tombait du ciel, mais peu de gens savent ce qu\u2019ils feraient de cet argent, apr\u00e8s l\u2019avoir gagn\u00e9 \u00e9tape par \u00e9tape gr\u00e2ce \u00e0 leur activit\u00e9 professionnelle et en suivant des principes d\u2019enrichissement. Ces r\u00e8gles de conduite parfois draconiennes, qui vues d\u2019en bas, sont souvent jug\u00e9es avec n\u00e9gativit\u00e9.<\/p>\n<p>Contrairement \u00e0 ce que la plupart des gens peuvent penser, pour faire fortune progressivement, le niveau de Conscience requis est tr\u00e8s \u00e9lev\u00e9. Vivre riche, c\u2019est vivre coupable aux yeux de millions de personnes. <strong>Imaginez la force de caract\u00e8re qu\u2019il faut pour s\u2019affirmer<\/strong> dans un monde qui vous juge \u00e0 travers l\u2019argent que vous poss\u00e9dez, la voiture dans laquelle vous roulez, les cadeaux que vous offrez \u00e0 vos enfants&#8230;<\/p>\n<ul>\n<li>Oh, me direz-vous, ne les plaignez pas\u00a0! Il y a des gens bien plus malheureux qui n\u2019arrivent pas \u00e0 s\u2019affirmer dans ce monde cruel&#8230;<\/li>\n<\/ul>\n<p>Je ne les plains pas. D\u2019ailleurs ils ne se plaignent pas non plus, car un jour ils y ont renonc\u00e9. Ce jour-l\u00e0 ils ont entam\u00e9 leur chemin vers la fortune. C\u2019est un autre principe de base\u00a0: passer \u00e0 l\u2019action pour arranger les choses, au lieu de se plaindre \u00e0 propos de tout ce qui ne va pas&#8230; Eh oui, je vous parlais de r\u00e8gles de conduite draconiennes\u00a0!<\/p>\n<p>Savez-vous faire la diff\u00e9rence entre vos <strong>besoins <\/strong>et vos <strong>envies<\/strong>\u00a0? Un futur millionnaire fait la diff\u00e9rence instantan\u00e9ment. Ceci ne signifie pas qu\u2019il ne se fait jamais plaisir. Au contraire\u00a0: au moment d\u2019acheter l\u2019objet de ses envies, de beaux sentiments le traversent, car il sait qu\u2019il vient de s\u2019offrir un cadeau\u00a0: aucun sentiment d\u2019obligation n\u2019a pr\u00e9c\u00e9d\u00e9 cet achat, et aucune culpabilit\u00e9 ne suivra. Il ne se dira pas \u00abBon bein maintenant, il va falloir se serrer la ceinture\u00a0!\u00bb, car comme nous l\u2019avons vu dans la premi\u00e8re partie de cet article, en ce qui concerne ses envies, il respecte \u00abreligieusement\u00bb une loi : m\u00eame si la tentation est grande, il ne s\u2019ach\u00e8te pas de produits haut de gamme, \u00e0 moins de disposer d\u2019une somme 20 fois sup\u00e9rieure au prix de l\u2019objet convoit\u00e9.<\/p>\n<p>Nous appellerons ce principe, \u00abla loi du vingti\u00e8me\u00bb.<\/p>\n<p>Dans mon pr\u00e9c\u00e9dent article, j\u2019ai bien pr\u00e9cis\u00e9 que la loi du vingti\u00e8me ne s\u2019appliquait pas en toutes circonstances. Elle appara\u00eet automatiquement face \u00e0 un iPhone ou un Samsung derni\u00e8re g\u00e9n\u00e9ration (envie), mais elle reste en sommeil si le t\u00e9l\u00e9phone \u00e0 acqu\u00e9rir r\u00e9pond au strict minimum (besoin). C\u2019est aussi l\u00e0 un point fort des personnes qui construisent leur vie\u00a0: un t\u00e9l\u00e9phone n\u2019est pas un besoin physiologique (comme manger, boire ou dormir), mais si vous exercez une activit\u00e9 professionnelle qui n\u00e9cessite une certaine mobilit\u00e9, il convient de reconna\u00eetre le t\u00e9l\u00e9phone mobile comme un besoin, tout en reconnaissant que le dernier mod\u00e8le de chez Apple ou Samsung sont des envies.<\/p>\n<p>J\u2019ai termin\u00e9 mon article en proposant de r\u00e9soudre une \u00e9nigme\u00a0: j\u2019\u00e9voque le fait que face \u00e0 certaines d\u00e9penses qui pourraient appara\u00eetre comme un luxe, la loi du vingti\u00e8me s\u2019incline. La question \u00e9tait\u00a0: \u00e0 votre avis, dans quels cas cela se produit\u00a0?<\/p>\n<h2>L\u2019investissement<\/h2>\n<p>Sous mon article, un certain nombre de r\u00e9ponses ont \u00e9t\u00e9 propos\u00e9es\u00a0concernant <strong>les investissements<\/strong>. Jos\u00e9 et Frederic ont \u00e9t\u00e9 les premiers \u00e0 en parler et \u00e0 donner des exemples qui consistent \u00e0 acheter, transformer et revendre en faisant un b\u00e9n\u00e9fice. Effectivement, l\u2019investissement annule la r\u00e8gle du vingti\u00e8me. Vous pourriez m\u00eame acheter un stock de produits avec de l\u2019argent que vous n\u2019avez pas encore, pour saisir une opportunit\u00e9 (en empruntant).<\/p>\n<h2>Les Valeurs Fondamentales<\/h2>\n<p>Un autre style de d\u00e9pense concerne les Valeurs Fondamentales. Par exemple, la <strong>Sant\u00e9<\/strong>. Les millionnaires ne se satisfont pas des soins rembours\u00e9s par la S\u00e9cu. La raison est tr\u00e8s simple\u00a0: l\u2019Assurance Maladie prend en charge les malades. Or il est possible d\u2019\u00e9viter certaines maladies en agissant en amont sur le bien-\u00eatre et la forme physique. Lorsque la Sant\u00e9 est une Valeur Fondamentale clairement assum\u00e9e, les produits et les services qui lui sont li\u00e9s n\u2019apparaissent plus comme du \u00abhaut de gamme\u00bb. La loi du vingti\u00e8me ne s\u2019applique plus. Ainsi, un futur millionnaire qui dispose de 10.000\u20ac, s\u2019abonnera sans sourciller \u00e0 des activit\u00e9s sportives \u00e0 hauteur de 800\u20ac, alors qu\u2019un iPhone lui para\u00eetra hors de prix (puisqu\u2019il lui manquera encore 6.000\u20ac pour pouvoir se l\u2019offrir).<\/p>\n<p>Ce que je viens d\u2019\u00e9crire \u00e0 propos de la Sant\u00e9, est valable pour toutes vos Valeurs Fondamentales\u00a0: si un voyage \u00e0 Venise une fois par an, entretient l\u2019<strong>Harmonie de votre couple<\/strong>, en futur millionnaire n\u2019h\u00e9sitez pas \u00e0 mettre de c\u00f4t\u00e9 la loi du vingti\u00e8me. Mais veillez \u00e0 bien observer la limite entre vos besoins et vos envies pendant le voyage\u00a0: le fait de voyager en premi\u00e8re classe et de boire une coupe de champagne dans l\u2019avion fait-il partie de ce besoin d\u2019Harmonie\u00a0? Si c\u2019est un rituel attendu, un clin d\u2019\u0153il \u00e0 la vie dont votre couple a le secret, faites dispara\u00eetre la loi du vingti\u00e8me. Mais si c\u2019est une envie soudaine parce que vous voulez faire comme votre voisin, c\u2019est peut-\u00eatre tr\u00e8s au-dessus de vos moyens.<\/p>\n<p>Je pourrais en dire autant \u00e0 propos de l\u2019Education de vos enfants, de la Solidarit\u00e9, de l\u2019Amiti\u00e9&#8230; Si vous l\u00e2chez vos Valeurs pour faire des \u00e9conomies, il vous sera difficile de gagner de l\u2019argent. Si vous amplifiez votre personnalit\u00e9 en affirmant vos Valeurs, vous vous attirerez des opportunit\u00e9s d\u2019argent qui les sublimeront davantage.<\/p>\n<p>L\u2019argent a une odeur, contrairement \u00e0 ce que dit le dicton populaire. Ce dicton est faiseur de pauvres\u00a0! Chassez-le de votre esprit, ou relativisez-le.<\/p>\n<h2>Les formations<\/h2>\n<p>Frederic a \u00e9voqu\u00e9 <strong>la Formation<\/strong> comme une d\u00e9pense l\u00e9gitime qui sort du cadre de la loi du vingti\u00e8me. C\u2019est une \u00e9vidence\u00a0! J\u2019entends tellement de gens me dire \u00abcette Formation est un luxe que je ne peux pas me payer&#8230;\u00bb que j\u2019en ai le souffle coup\u00e9\u00a0! Les entrepreneurs qui r\u00e9ussissent se forment\u00a0r\u00e9guli\u00e8rement. Les entreprises prosp\u00e8res forment leur personnel et veillent \u00e0 recruter des personnes qui aiment se former.<\/p>\n<p>Vous voulez un secret de polichinelle\u00a0? Il s\u2019agit d\u2019une phrase \u00e0 placer lors d\u2019un entretien d\u2019embauche. A la question\u00a0:<\/p>\n<p>&#8211; Savez-vous utiliser PROJECT 2016\u00a0?<\/p>\n<p>R\u00e9pondez\u00a0:<\/p>\n<p>&#8211; Non\u00a0! Mais je peux apprendre&#8230; J\u2019aime apprendre\u00a0!<\/p>\n<p>Cette r\u00e9ponse est meilleure qu\u2019un OUI. 100 fois meilleure\u00a0! Et si le recruteur vous r\u00e9pond \u00abDommage\u00a0! A part \u00e7a, vous aviez le meilleur profil&#8230;\u00bb, c\u2019est que la soci\u00e9t\u00e9 qui l\u2019a mandat\u00e9e ne vous m\u00e9rite pas\u00a0!<\/p>\n<p>Autorisez-vous \u00e0 faire de la Formation un automatisme. Une \u00e9vidence\u00a0! \u00c7a ouvre des portes\u00a0!<\/p>\n<p>Revenons \u00e0 notre sujet\u00a0: les futurs millionnaires se forment en permanence, que ce soit en conf\u00e9rence, dans une salle confidentielle ou en solo devant leur \u00e9cran, ils ont besoin de nouvelles connaissances pour progresser. C\u2019est impossible autrement. Mais il y a deux types de formations qu\u2019il convient de distinguer\u00a0:<\/p>\n<ul>\n<li>Les premi\u00e8res sont qualifi\u00e9es de<strong> \u00abcentrales\u00bb<\/strong>. Un dentiste qui vient de s\u2019\u00e9quiper d\u2019un nouveau mat\u00e9riel pour photographier la racine d\u2019une dent, ach\u00e8tera quelques heures de formation pour apprendre \u00e0 s\u2019en servir. C\u2019est central\u00a0!<\/li>\n<li>Beaucoup d\u2019autres formations sont qualifi\u00e9es de \u00abnon-centrales\u00bb. Par exemple \u00abLa Communication Intelligente\u00bb, ce n\u2019est pas central pour un dentiste\u00a0!<\/li>\n<\/ul>\n<p>Mais \u00e0 bien y r\u00e9fl\u00e9chir, est-ce que c\u2019est vraiment tordu de proposer \u00e0 un dentiste une formation qui lui permettra de rassurer ses clients\u00a0? 7 personnes sur 10 ont encore peur du dentiste, alors que ces 10 derni\u00e8res ann\u00e9es ils se sont form\u00e9s aux meilleures innovations qui permettent de limiter les extractions et r\u00e9duire la douleur. Et s\u2019il suffisait de communiquer pour r\u00e9duire la peur\u00a0?<\/p>\n<p>Si vous proposez \u00e0 un millionnaire de suivre une formation sur l\u2019achat et la revente d\u2019or \u00e0 travers le monde, il va peut-\u00eatre h\u00e9siter avant de dire oui (ou non). Mais si vous lui proposez de suivre une formation qui lui permettra de r\u00e9v\u00e9ler et de renforcer ses Valeurs Fondamentales, il n\u2019h\u00e9sitera pas une seconde.<\/p>\n<p>Pourquoi\u00a0? Parce qu\u2019il ne faut pas se leurrer\u00a0: un millionnaire ne vit pas sur une autre plan\u00e8te. Face \u00e0 un voyage de r\u00eave, une voiture de course, une maison de caract\u00e8re&#8230; la tentation est grande, et personne ne l\u2019oblige \u00e0 respecter des lois draconiennes\u00a0; ce sont des lois int\u00e9rieures. Les formations dites \u00abnon-centrales\u00bb lui permettent de se renforcer int\u00e9rieurement. Il est le mieux plac\u00e9 pour savoir que \u00e7a vaut tout l\u2019or du monde.<\/p>\n<p>A++<\/p>\n<p><strong>St\u00e9phane SOLOMON<\/strong><\/p>\n<p>&#8212;-<\/p>\n<figure style=\"width: 464px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.vpc-concept.fr\/catalogue\/ecole_francaise_d_auto_coaching\/formation_communication_intelligente.html\"><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"http:\/\/www.vpc-concept.fr\/images\/produits\/produit_402_home.gif\" alt=\"Formation : La Communication Intelligente\" width=\"464\" height=\"348\" \/><\/a><figcaption class=\"wp-caption-text\">Formation : La Communication Intelligente<\/figcaption><\/figure>\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-2825\" data-postid=\"2825\" class=\"themify_builder_content themify_builder_content-2825 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>Mercredi dernier nous avons eu de l\u2019animation\u00a0: plusieurs dizaines de commentaires\u00a0! Il semble que la question d\u2019argent int\u00e9resse beaucoup de monde, m\u00eame si souvent, on me ram\u00e8ne vers le fameux \u00abL\u2019argent ne fait pas le Bonheur\u00a0!\u00bb. C\u2019est tr\u00e8s juste. L\u2019argent n\u2019est pas g\u00e9n\u00e9rateur, mais amplificateur. Il amplifie ce que vous avez en vous. Il donne [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_options":[]},"categories":[1],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/auto-coaching.fr\/wp-content\/uploads\/2016\/02\/million.png","builder_content":"","_links":{"self":[{"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/posts\/2825"}],"collection":[{"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2825"}],"version-history":[{"count":5,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/posts\/2825\/revisions"}],"predecessor-version":[{"id":2833,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/posts\/2825\/revisions\/2833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/media\/2826"}],"wp:attachment":[{"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auto-coaching.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}